{"id":185,"date":"2018-02-22T12:37:06","date_gmt":"2018-02-22T12:37:06","guid":{"rendered":"http:\/\/xanatis.com\/~abogadoslacaba\/?page_id=185"},"modified":"2024-04-24T20:35:15","modified_gmt":"2024-04-24T19:35:15","slug":"politica-de-privacitat","status":"publish","type":"page","link":"https:\/\/abogadoslacaba.com\/ca\/politica-de-privacitat\/","title":{"rendered":"Pol\u00edtica de privacitat"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"185\" class=\"elementor elementor-185 elementor-183\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c53747d e-flex e-con-boxed e-con e-parent\" data-id=\"c53747d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c50ec3b elementor-widget elementor-widget-heading\" data-id=\"4c50ec3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pol\u00edtica de privacidad<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b488f66 elementor-widget elementor-widget-heading\" data-id=\"4b488f66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Datos del propietario de la web\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-650739b1 elementor-widget elementor-widget-text-editor\" data-id=\"650739b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table>\n<tr>\n<td style=\"background:#F0F0F0; font-weight: bold\">RAZ\u00d3N SOCIAL<\/td>\n<td style=\"background:#FFF\">LACABA ABOGADOS SL<\/td>\n<\/tr>\n<tr>\n<td  style=\"background:#F0F0F0; font-weight: bold\">NIF<\/td>\n<td style=\"background:#FFF\">B66888959<\/td>\n<\/tr>\n\n<tr>\n<td  style=\"background:#F0F0F0; font-weight: bold\">DOMINIO <\/td>\n<td style=\"background:#FFF\">WWW.ABOGADOSLACABA.COM<\/td>\n<\/tr>\n\n<tr>\n<td  style=\"background:#F0F0F0; font-weight: bold\">DIRECCI\u00d3N POSTAL<\/td>\n<td style=\"background:#FFF\">ANSELM CLAVE 9,08290 CERDANYOLA DEL VALLES(BARCELONA)<\/td>\n<\/tr>\n\n<tr>\n<td  style=\"background:#F0F0F0; font-weight: bold\">DIRECCI\u00d3N\nELECTR\u00d3NICA <\/td>\n<td style=\"background:#FFF\">j.lacaba@abogadoslacaba.com<\/td>\n<\/tr>\n\n<tr>\n<td  style=\"background:#F0F0F0; font-weight: bold\">TEL\u00c9FONOS <\/td>\n<td style=\"background:#FFF\">936927308<\/td>\n<\/tr>\n\n\n<tr>\n<td  style=\"background:#F0F0F0; font-weight: bold\">DATOS\nADICIONALES<\/td>\n<td style=\"background:#FFF\"><\/td>\n<\/tr>\n\n<\/table>\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6eaf2b6 elementor-widget elementor-widget-heading\" data-id=\"6eaf2b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Protecci\u00f3n de datos\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2db7e73f elementor-widget elementor-widget-text-editor\" data-id=\"2db7e73f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>De conformidad con la normativa vigente y aplicable en protecci\u00f3n de datos de car\u00e1cter personal, le informamos que sus datos ser\u00e1n incorporados al sistema de tratamiento titularidad de LACABA ABOGADOS SL con NIF B66888959 y domicilio social sito en ANSELM CLAVE 9,08290 CERDANYOLA DEL VALLES(BARCELONA), y que a continuaci\u00f3n se relacionan sus respectivas finalidades, plazos de conservaci\u00f3n y bases legitimadoras:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f815a47 elementor-widget elementor-widget-text-editor\" data-id=\"4f815a47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><td style=\"background: #F0F0F0; font-weight: bold;\">Acciones<br \/>comerciales<br \/>formulario web<\/td><td style=\"background: #FFF;\"><strong>Finalidad<\/strong>: Captaci\u00f3n, registro y tratamiento de datos con finalidades de atender sus consultas y\/o solicitudes, as\u00ed como de publicidad y prospecci\u00f3n comercial<br \/><strong>Plazo de conservaci\u00f3n:<\/strong> mientras se mantenga el consentimiento prestado, salvo obligaci\u00f3n legal.<br \/><strong>Base leg\u00edtima:<\/strong> El consentimiento del interesado.<br \/>Tipolog\u00eda de Datos: Datos b\u00e1sicos: Nombre y apellidos, Direcci\u00f3n electr\u00f3nica<\/td><\/tr><tr><td style=\"background: #F0F0F0; font-weight: bold;\">Gesti\u00f3n usuarios<br \/>web<\/td><td style=\"background: #FFF;\"><b>Finalidad<\/b>: Captaci\u00f3n, registro y tratamiento de datos del usuario<br \/><b>Plazo de conservaci\u00f3n<\/b>: mientras se mantenga el consentimiento prestado, salvo<br \/>obligaci\u00f3n legal.<br \/><b>Base leg\u00edtima<\/b>: El consentimiento del interesado.<br \/><b>Tipolog\u00eda de Datos:<\/b> Datos b\u00e1sicos: Nombre y apellidos, Direcci\u00f3n electr\u00f3nica<\/td><\/tr><tr><td style=\"background: #F0F0F0; font-weight: bold;\">Newsletter<\/td><td style=\"background: #FFF;\"><b>Finalidad<\/b>: Gesti\u00f3n de la suscripci\u00f3n a la newsletter, para realizar los env\u00edos<br \/>correspondientes<br \/><b>Plazo de conservaci\u00f3n<\/b>: mientras se mantenga el consentimiento prestado.<br \/><b>Base leg\u00edtima:<\/b> El consentimiento del interesado.<br \/><b>Tipolog\u00eda de Datos<\/b>: Datos b\u00e1sicos: Nombre y apellidos, Direcci\u00f3n electr\u00f3nica<\/td><\/tr><tr><td style=\"background: #F0F0F0; font-weight: bold;\">Instalaci\u00f3n de<br \/>cookies<\/td><td style=\"background: #FFF;\"><b>Finalidad<\/b>: Gesti\u00f3n e instalaci\u00f3n de las cookies<br \/><b> Plazo de conservaci\u00f3n<\/b>: mientras se mantenga el consentimiento prestado.<br \/><b> Base leg\u00edtima<\/b>: El consentimiento del interesado.<br \/>Tipolog\u00eda de Datos: Datos b\u00e1sicos: Direcci\u00f3n electr\u00f3nica, Direcci\u00f3n IP<\/td><\/tr><tr><td style=\"background: #F0F0F0; font-weight: bold;\">Gesti\u00f3n Formulario web<\/td><td style=\"background: #FFF;\"><b>Finalidad<\/b>: Atender sus consultas y\/o solicitudes <br \/><b>Plazo de conservaci\u00f3n:<\/b> mientras se mantenga el consentimiento prestado. <br \/><b>Base leg\u00edtima:<\/b> El consentimiento del interesado. <br \/><b>Tipolog\u00eda de Datos:<\/b> Datos b\u00e1sicos: Nombre y apellidos, Direcci\u00f3n electr\u00f3nica, Direcci\u00f3n IP<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31cfa02c elementor-widget elementor-widget-heading\" data-id=\"31cfa02c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Derechos de los interesados\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14fc3529 elementor-widget elementor-widget-text-editor\" data-id=\"14fc3529\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>LACABA ABOGADOS SL informa a los Usuarios que, podr\u00e1 ejercer los derechos de acceso, rectificaci\u00f3n,limitaci\u00f3n, supresi\u00f3n, portabilidad, oposici\u00f3n al\u00a0 tratamiento de sus datos de car\u00e1cter personal y el derecho a no ser objeto de decisiones automatizadas, incluida la elaboraci\u00f3n de perfiles, ante el Responsable del Tratamiento, as\u00ed como a la retirada del consentimiento prestado.<\/p><ul><li>Derecho de Acceso: Es el derecho del usuario a obtener confirmaci\u00f3n sobre si se est\u00e1n tratando sus datos y, en tal caso, los concretos datos personales tratados y la informaci\u00f3n legal del tratamiento (finalidades, base legitimadora, plazos de conservaci\u00f3n, cesiones, origen de los datos, etc.).<\/li><li>Derecho de Rectificaci\u00f3n: Es el derecho del afectado a que se modifiquen los datos que resulten ser inexactos o incompletos. En relaci\u00f3n a la p\u00e1gina web, s\u00f3lo podr\u00e1 satisfacerse en relaci\u00f3n a aquella informaci\u00f3n que se encuentre bajo el control del sitio web, por ejemplo, eliminar comentarios publicados en la propia p\u00e1gina, im\u00e1genes o contenidos web donde consten datos de car\u00e1cter personal del usuario.<\/li><li>Derecho a la Limitaci\u00f3n de tratamiento: Es el derecho a que se limiten los fines del tratamiento previstos de forma original por el responsable del tratamiento en determinados supuestos.<\/li><li>Derecho de Supresi\u00f3n: Es el derecho a suprimir los datos de car\u00e1cter personal del usuario, a excepci\u00f3n de lo previsto en el propio RGPD (libertad de expresi\u00f3n e informaci\u00f3n, obligaciones de conservaci\u00f3n, formulaci\u00f3n, ejercicio o defensa de reclamaciones, etc.).<\/li><li>Derecho a la Portabilidad: El derecho a recibir los datos personales que el usuario haya facilitado, en un formato estructurado, de uso com\u00fan y lectura mec\u00e1nica, y a transmitirlos a otro responsable cuando medidas para el cumplimiento normativo \u00b7 servicio compliance el tratamiento est\u00e1 basado en el consentimiento o en la ejecuci\u00f3n de un contrato y se efect\u00fae por medios automatizados.<\/li><li>Derecho de Oposici\u00f3n: Es el derecho del usuario a que no se lleve a cabo el tratamiento de sus datos de car\u00e1cter personal o se cese el tratamiento de los mismos por parte del sitio web cuando el tratamiento est\u00e9 basado en el inter\u00e9s leg\u00edtimo o el inter\u00e9s p\u00fablico o cuando se trate de tratamientos de<\/li><li>mercadotecnia directa.<\/li><li>Derecho a no ser objeto de decisiones automatizadas, incluida la elaboraci\u00f3n de perfiles: Cuando el tratamiento no es necesario para la celebraci\u00f3n o ejecuci\u00f3n de un contrato, ni est\u00e1 autorizada por el Derecho de la Uni\u00f3n Europea o de los Estados miembros ni se basa en el consentimiento, tiene derecho a no ser objeto de una decisi\u00f3n basada \u00fanicamente en el tratamiento automatizado, incluida la elaboraci\u00f3n de perfiles, que produzca efectos jur\u00eddicos o le afecte significativamente de modo similar.<\/li><li>Derecho a retirar el consentimiento: Para cualquier tratamiento basado en su consentimiento, tiene derecho a retirarlo, en cualquier momento y de manera gratuita.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62d9df66 elementor-widget elementor-widget-text-editor\" data-id=\"62d9df66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Para ejercer cualquiera de los derechos en materia de protecci\u00f3n de datos descritos anteriormente deber\u00e1 seguir las siguientes indicaciones:<\/p><ul><li>Presentaci\u00f3n de un escrito a la direcci\u00f3n ANSELM CLAVE 9,08290 CERDANYOLA DEL VALLES(BARCELONA) (a la atenci\u00f3n de LACABA ABOGADOS SL) o bien a trav\u00e9s de correo electr\u00f3nico a por correo electr\u00f3nico a j.lacaba@abogadoslacaba.com .<\/li><li>El escrito remitido por el titular de los datos personales (interesado\/a) que solicite el ejercicio de derechos deber\u00e1 tener en cuenta lo siguiente:<\/li><\/ul><div>\u00a0<\/div><ol><li style=\"list-style-type: none;\"><ul><li><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">Deber\u00e1 identificarse fehacientemente y, en el caso de que concurran dudas sobre la identidad <\/span><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">del solicitante, se le solicitar\u00e1 que subsane la petici\u00f3n (p. ej. solicitando m\u00e1s informaci\u00f3n, como <\/span><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">el n\u00famero de DNI, el documento del DNI, el correo electr\u00f3nico que aport\u00f3, etc.)<\/span><\/li><li><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">La solicitud puede realizarla el representante, legal o voluntario, cuando \u00e9ste est\u00e9 debidamente <\/span><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">identificado y autorizado por el titular de los datos (mediante una autorizaci\u00f3n expresa del <\/span><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">titular para ejercer los derechos personal\u00edsimos regulados en la normativa en materia de <\/span><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">protecci\u00f3n de datos personales).<\/span><\/li><li><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">Petici\u00f3n en que se concreta la solicitud (Derecho\/s que se pretende\/n ejercer). Si no hace <\/span><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">referencia a un tratamiento concreto se le facilitar\u00e1 respuesta en relaci\u00f3n a todos los <\/span><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">tratamientos que afectan a sus datos de car\u00e1cter personal. Si solicita informaci\u00f3n de un <\/span><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">tratamiento en concreto, s\u00f3lo la informaci\u00f3n de \u00e9ste. Si lo solicita por tel\u00e9fono se le indicar\u00e1 <\/span><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">que lo haga por escrito y se le informar\u00e1 de c\u00f3mo lo puede hacer y la direcci\u00f3n a la que tiene <\/span><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">que enviarlo. Nunca se le dar\u00e1 informaci\u00f3n por tel\u00e9fono.<\/span><\/li><li><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">Direcci\u00f3n postal o electr\u00f3nica a efectos de notificaciones.<\/span><\/li><li><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">Documentos acreditativos de la petici\u00f3n que formula, en caso de que sean necesarios.<\/span><\/li><li><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">La persona solicitante debe utilizar cualquier medio que permita acreditar el env\u00edo y la <\/span><span style=\"background-color: transparent; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">recepci\u00f3n de la solicitud.<\/span><\/li><\/ul><\/li><\/ol><p style=\"padding-left: 40px;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6744636b elementor-widget elementor-widget-text-editor\" data-id=\"6744636b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Por \u00faltimo, le informamos que tiene derecho a presentar una reclamaci\u00f3n ante la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos en caso de que tenga conocimiento o considere que un hecho pueda suponer un incumplimiento de la normativa aplicable en materia de protecci\u00f3n de datos.<br \/>LACABA ABOGADOS SL se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, acorde al nivel de riesgos que acompa\u00f1an los tratamientos realizados por \u00e9stas e indicados en el apartado de los t\u00e9rminos y condiciones de uso, de forma que garanticen su integridad, confidencialidad y disponibilidad.<br \/><br \/><\/p><p><b>\u00daltima actualizaci\u00f3n: <\/b>22 de abril de 2024<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de privacidad Datos del propietario de la web RAZ\u00d3N SOCIAL LACABA ABOGADOS SL NIF B66888959 DOMINIO WWW.ABOGADOSLACABA.COM DIRECCI\u00d3N POSTAL ANSELM CLAVE 9,08290 CERDANYOLA DEL VALLES(BARCELONA) DIRECCI\u00d3N ELECTR\u00d3NICA j.lacaba@abogadoslacaba.com TEL\u00c9FONOS 936927308 DATOS ADICIONALES Protecci\u00f3n de datos De conformidad con la normativa vigente y aplicable en protecci\u00f3n de datos de car\u00e1cter personal, le informamos que sus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-185","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de privacitat - Abogados Lacaba<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abogadoslacaba.com\/ca\/politica-de-privacitat\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de privacitat - Abogados Lacaba\" \/>\n<meta property=\"og:description\" content=\"Pol\u00edtica de privacidad Datos del propietario de la web RAZ\u00d3N SOCIAL LACABA ABOGADOS SL NIF B66888959 DOMINIO WWW.ABOGADOSLACABA.COM DIRECCI\u00d3N POSTAL ANSELM CLAVE 9,08290 CERDANYOLA DEL VALLES(BARCELONA) DIRECCI\u00d3N ELECTR\u00d3NICA j.lacaba@abogadoslacaba.com TEL\u00c9FONOS 936927308 DATOS ADICIONALES Protecci\u00f3n de datos De conformidad con la normativa vigente y aplicable en protecci\u00f3n de datos de car\u00e1cter personal, le informamos que sus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abogadoslacaba.com\/ca\/politica-de-privacitat\/\" \/>\n<meta property=\"og:site_name\" content=\"Abogados Lacaba\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-24T19:35:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@lacabaabogados\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/abogadoslacaba.com\\\/ca\\\/politica-de-privacitat\\\/\",\"url\":\"https:\\\/\\\/abogadoslacaba.com\\\/ca\\\/politica-de-privacitat\\\/\",\"name\":\"Pol\u00edtica de privacitat - Abogados Lacaba\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/abogadoslacaba.com\\\/ca\\\/#website\"},\"datePublished\":\"2018-02-22T12:37:06+00:00\",\"dateModified\":\"2024-04-24T19:35:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/abogadoslacaba.com\\\/ca\\\/politica-de-privacitat\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/abogadoslacaba.com\\\/ca\\\/politica-de-privacitat\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/abogadoslacaba.com\\\/ca\\\/politica-de-privacitat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/abogadoslacaba.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de privacitat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/abogadoslacaba.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/abogadoslacaba.com\\\/ca\\\/\",\"name\":\"Abogados Lacaba\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/abogadoslacaba.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/abogadoslacaba.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/abogadoslacaba.com\\\/ca\\\/#organization\",\"name\":\"Lacaba Abogados\",\"url\":\"https:\\\/\\\/abogadoslacaba.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/abogadoslacaba.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/abogadoslacaba.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/iJHgrQ4q.jpg\",\"contentUrl\":\"https:\\\/\\\/abogadoslacaba.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/iJHgrQ4q.jpg\",\"width\":512,\"height\":512,\"caption\":\"Lacaba Abogados\"},\"image\":{\"@id\":\"https:\\\/\\\/abogadoslacaba.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/lacabaabogados\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacitat - Abogados Lacaba","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abogadoslacaba.com\/ca\/politica-de-privacitat\/","og_locale":"ca_ES","og_type":"article","og_title":"Pol\u00edtica de privacitat - Abogados Lacaba","og_description":"Pol\u00edtica de privacidad Datos del propietario de la web RAZ\u00d3N SOCIAL LACABA ABOGADOS SL NIF B66888959 DOMINIO WWW.ABOGADOSLACABA.COM DIRECCI\u00d3N POSTAL ANSELM CLAVE 9,08290 CERDANYOLA DEL VALLES(BARCELONA) DIRECCI\u00d3N ELECTR\u00d3NICA j.lacaba@abogadoslacaba.com TEL\u00c9FONOS 936927308 DATOS ADICIONALES Protecci\u00f3n de datos De conformidad con la normativa vigente y aplicable en protecci\u00f3n de datos de car\u00e1cter personal, le informamos que sus [&hellip;]","og_url":"https:\/\/abogadoslacaba.com\/ca\/politica-de-privacitat\/","og_site_name":"Abogados Lacaba","article_modified_time":"2024-04-24T19:35:15+00:00","twitter_card":"summary_large_image","twitter_site":"@lacabaabogados","twitter_misc":{"Temps estimat de lectura":"7 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/abogadoslacaba.com\/ca\/politica-de-privacitat\/","url":"https:\/\/abogadoslacaba.com\/ca\/politica-de-privacitat\/","name":"Pol\u00edtica de privacitat - Abogados Lacaba","isPartOf":{"@id":"https:\/\/abogadoslacaba.com\/ca\/#website"},"datePublished":"2018-02-22T12:37:06+00:00","dateModified":"2024-04-24T19:35:15+00:00","breadcrumb":{"@id":"https:\/\/abogadoslacaba.com\/ca\/politica-de-privacitat\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abogadoslacaba.com\/ca\/politica-de-privacitat\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/abogadoslacaba.com\/ca\/politica-de-privacitat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/abogadoslacaba.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de privacitat"}]},{"@type":"WebSite","@id":"https:\/\/abogadoslacaba.com\/ca\/#website","url":"https:\/\/abogadoslacaba.com\/ca\/","name":"Abogados Lacaba","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/abogadoslacaba.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abogadoslacaba.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/abogadoslacaba.com\/ca\/#organization","name":"Lacaba Abogados","url":"https:\/\/abogadoslacaba.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/abogadoslacaba.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/abogadoslacaba.com\/wp-content\/uploads\/2019\/06\/iJHgrQ4q.jpg","contentUrl":"https:\/\/abogadoslacaba.com\/wp-content\/uploads\/2019\/06\/iJHgrQ4q.jpg","width":512,"height":512,"caption":"Lacaba Abogados"},"image":{"@id":"https:\/\/abogadoslacaba.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/lacabaabogados"]}]}},"_links":{"self":[{"href":"https:\/\/abogadoslacaba.com\/ca\/wp-json\/wp\/v2\/pages\/185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abogadoslacaba.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/abogadoslacaba.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/abogadoslacaba.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/abogadoslacaba.com\/ca\/wp-json\/wp\/v2\/comments?post=185"}],"version-history":[{"count":6,"href":"https:\/\/abogadoslacaba.com\/ca\/wp-json\/wp\/v2\/pages\/185\/revisions"}],"predecessor-version":[{"id":1284,"href":"https:\/\/abogadoslacaba.com\/ca\/wp-json\/wp\/v2\/pages\/185\/revisions\/1284"}],"wp:attachment":[{"href":"https:\/\/abogadoslacaba.com\/ca\/wp-json\/wp\/v2\/media?parent=185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}